{"id":28011,"date":"2026-07-15T09:40:11","date_gmt":"2026-07-15T07:40:11","guid":{"rendered":"https:\/\/ettelbruck.lu\/citoyen\/?post_type=actualite&#038;p=28011"},"modified":"2026-07-15T09:43:01","modified_gmt":"2026-07-15T07:43:01","slug":"17-juillet-nettoyage-dune-surface-en-pierre-dans-la-cite-waarkdall-n35-a-warken","status":"publish","type":"actualite","link":"https:\/\/ettelbruck.lu\/citoyen\/actualite\/17-juillet-nettoyage-dune-surface-en-pierre-dans-la-cite-waarkdall-n35-a-warken\/","title":{"rendered":"17 juillet : Nettoyage d&rsquo;une surface en pierre dans la Cit\u00e9 Waarkdall N\u00b035 \u00e0 Warken"},"content":{"rendered":"<p>Le r\u00e8glement de la circulation de la Ville d&rsquo;Ettelbruck sera modifi\u00e9 le vendredi 17 juillet 2026 (08h00 &#8211; 17h00) :<\/p>\n<ul>\n<li>La Cit\u00e9 Waarkdall est r\u00e9tr\u00e9cie \u00e0 la hauteur de la maison N\u00b0 35<\/li>\n<\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le r\u00e8glement de la circulation de la Ville d&rsquo;Ettelbruck sera modifi\u00e9 le vendredi 17 juillet 2026 (08h00 &#8211; 17h00) : La Cit\u00e9 Waarkdall est r\u00e9tr\u00e9cie \u00e0 la hauteur de la maison N\u00b0 35<\/p>\n","protected":false},"featured_media":25117,"template":"","acf":[],"_links":{"self":[{"href":"https:\/\/ettelbruck.lu\/citoyen\/wp-json\/wp\/v2\/actualite\/28011"}],"collection":[{"href":"https:\/\/ettelbruck.lu\/citoyen\/wp-json\/wp\/v2\/actualite"}],"about":[{"href":"https:\/\/ettelbruck.lu\/citoyen\/wp-json\/wp\/v2\/types\/actualite"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ettelbruck.lu\/citoyen\/wp-json\/wp\/v2\/media\/25117"}],"wp:attachment":[{"href":"https:\/\/ettelbruck.lu\/citoyen\/wp-json\/wp\/v2\/media?parent=28011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}